{"id":13553,"date":"2025-01-29T12:49:27","date_gmt":"2025-01-29T12:49:27","guid":{"rendered":"https:\/\/alminutonoticia.com\/noticias\/?p=13553"},"modified":"2025-01-29T12:49:30","modified_gmt":"2025-01-29T12:49:30","slug":"aprehenden-a-50-personas-en-la-operacion-dignidad","status":"publish","type":"post","link":"https:\/\/alminutonoticia.com\/noticias\/aprehenden-a-50-personas-en-la-operacion-dignidad\/","title":{"rendered":"Aprehenden a 50 personas en la operaci\u00f3n \u2018Dignidad\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Procuradur\u00eda General de la Naci\u00f3n, a trav\u00e9s de diferentes Fiscal\u00edas Superiores, ha desarrollado 51 diligencias de allanamiento, en asocio con la Polic\u00eda Nacional, mediante la operaci\u00f3n \u00abDignidad\u00bb, aprehendiendo a 50 personas vinculadas a diversas investigaciones relacionadas con delitos sexuales, lesiones personales, robos, hurtos y robos de autos, estafa y delitos financieros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Procurador General de la Naci\u00f3n, Luis Carlos G\u00f3mez, inform\u00f3 que, dentro de la operaci\u00f3n, \u00abse ubicaron dos personas investigadas por delitos sexuales, quienes ten\u00edan bajo tenencia a dos menores de edad, una de ellas con un reporte de desaparecida, lo que es sumamente importante porque hace el reflejo de un desarrollo en positivo de estas diligencias que est\u00e1n realizando los agentes Fiscales con apoyo de los brazos auxiliares\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las diligencias se incautaron 85 municiones de armas de fuego, 25 celulares, 4 computadoras port\u00e1tiles, 6 USB, 10 tarjetas SD y 2 CPU.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los aprehendidos hay dos por delito de homicidio, uno por delito de homicidio en grado de tentativa, dos por blanqueo de capitales, 4 por robo agravado, 4 por delito de lesiones personales, 7 por delitos financieros, 3 por delito de violaci\u00f3n agravada, 6 por hurto de autos, 2 por estafa, uno por delitos relacionados con drogas, 3 por violencia de g\u00e9nero, 8 por delito contra el orden jur\u00eddico, 1 por maltrato al menor, por maltrato al adulto mayor, 1 por delito contra la administraci\u00f3n de justicia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por la Unidad de Delitos Sexuales de la Secci\u00f3n de Atenci\u00f3n Primaria de la Fiscal\u00eda Metropolitana, en donde a trav\u00e9s de monitoreos se pone en conocimientos de la presunta posesi\u00f3n, distribuci\u00f3n e intercambio de material pornogr\u00e1fico con menores de edad, que se ubican en el territorio de Panam\u00e1, donde se pudo determinar que las direcciones de los IP de donde se generaba la informaci\u00f3n, se encontraban en las \u00e1reas de Panam\u00e1 Norte y Panam\u00e1 Este. Los dispositivos incautados ser\u00e1n verificados por expertos forenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la&nbsp;<strong>Unidad de Hurto y Robo de Auto de la Secci\u00f3n de Atenci\u00f3n Primaria&nbsp;<\/strong>de la Fiscal\u00eda Metropolitana, investiga un grupo criminal que se dedicaba a alquilar veh\u00edculos, para cometer hurtos de autos en la urbe metropolitana, as\u00ed como personas vinculadas,&nbsp;<strong>a robos,<\/strong>&nbsp;a conductores de transporte selectivo y conductores de plataforma, quienes realizaban su carrera, y fueron despojados utilizando armas de fuego, de sus pertenencias, dinero en efectivo y de sus veh\u00edculos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, la Secci\u00f3n de Atenci\u00f3n Primaria y la Secci\u00f3n Segunda de Delitos contra el Patrimonio Econ\u00f3mico&nbsp;<strong>(Robo)&nbsp;<\/strong>de la Fiscal\u00eda Metropolitana, dio con la aprehensi\u00f3n de ciudadanos que se dedicaban a despojar a sus v\u00edctimas mediante intimidaci\u00f3n, utilizando armas de fuego, de sus pertenencias, tel\u00e9fonos celulares, dinero en efectivo y prendas. Estos hechos ocurrieron en el 2023 y 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la Secci\u00f3n Quinta de Delitos contra el Patrimonio Econ\u00f3mico (Estafa) investiga a un grupo dedicados al&nbsp;<strong>delito de estafa,&nbsp;<\/strong>quienes enga\u00f1an a sus v\u00edctimas ofreci\u00e9ndoles veh\u00edculos a precios llamativos, luego que las v\u00edctimas realizan la disposici\u00f3n patrimonial, pierden comunicaci\u00f3n y contacto con sus victimarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la Secci\u00f3n contra el&nbsp;<strong>Orden Econ\u00f3mico<\/strong>, a trav\u00e9s de estas acciones operativas ubic\u00f3 a personas relacionadas a investigaciones por delito financiero en su modalidad de documentaci\u00f3n falsa para obtener facilidades crediticias y blanqueo de capitales, en dos entidades bancarias del pa\u00eds, incluyendo una del estado, cuya afectaci\u00f3n econ\u00f3mica asciende los 500 mil balboas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas las personas aprehendidas ser\u00e1n puestas ante un Juez de Garant\u00edas en las pr\u00f3ximas horas, para solicitar la legalizaci\u00f3n de las aprehensiones, formulaci\u00f3n de imputaciones y aplicaci\u00f3n de medidas cautelares.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/alminutonoticia.com\/noticias\/wp-content\/uploads\/2025\/01\/procuraduria-770x470-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"770\" height=\"470\" src=\"https:\/\/alminutonoticia.com\/noticias\/wp-content\/uploads\/2025\/01\/procuraduria-770x470-1.jpg\" alt=\"\" class=\"wp-image-13554\" title=\"\" srcset=\"https:\/\/alminutonoticia.com\/noticias\/wp-content\/uploads\/2025\/01\/procuraduria-770x470-1.jpg 770w, https:\/\/alminutonoticia.com\/noticias\/wp-content\/uploads\/2025\/01\/procuraduria-770x470-1-300x183.jpg 300w, https:\/\/alminutonoticia.com\/noticias\/wp-content\/uploads\/2025\/01\/procuraduria-770x470-1-768x469.jpg 768w\" sizes=\"(max-width: 770px) 100vw, 770px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La Procuradur\u00eda General de la Naci\u00f3n, a trav\u00e9s de diferentes Fiscal\u00edas Superiores, ha desarrollado 51 diligencias de allanamiento, en asocio con la Polic\u00eda Nacional, mediante la operaci\u00f3n \u00abDignidad\u00bb, aprehendiendo a 50 personas vinculadas a diversas investigaciones relacionadas con delitos sexuales, lesiones personales, robos, hurtos y robos de autos, estafa y delitos financieros. El Procurador General [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-13553","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/posts\/13553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/comments?post=13553"}],"version-history":[{"count":1,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/posts\/13553\/revisions"}],"predecessor-version":[{"id":13555,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/posts\/13553\/revisions\/13555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/media\/13554"}],"wp:attachment":[{"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/media?parent=13553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/categories?post=13553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alminutonoticia.com\/noticias\/wp-json\/wp\/v2\/tags?post=13553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}